{"id":486,"date":"2013-01-10T12:57:08","date_gmt":"2013-01-10T12:57:08","guid":{"rendered":"http:\/\/www.boehlk.eu\/mittelalterorte\/?page_id=486"},"modified":"2015-01-16T12:44:01","modified_gmt":"2015-01-16T12:44:01","slug":"die-bernburger-burgkapelle-st-pankratius","status":"publish","type":"page","link":"https:\/\/www.boehlk.eu\/mittelalterorte\/die-bernburger-burgkapelle-st-pankratius\/","title":{"rendered":"Die Bernburger Burgkapelle St. Pankratius"},"content":{"rendered":"<div id=\"attachment_542\" style=\"width: 1010px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Montage-Burgkapelle-Korrekturen-Traeger_web.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-542\" class=\"size-full wp-image-542\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Montage-Burgkapelle-Korrekturen-Traeger_web.jpg\" alt=\"Schematische Rekonstruktion der Kubatur der Burgkapelle St. Pankratius auf dem Bernburger Schlosshof.\" width=\"1000\" height=\"805\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Montage-Burgkapelle-Korrekturen-Traeger_web.jpg 1000w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Montage-Burgkapelle-Korrekturen-Traeger_web-300x241.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Montage-Burgkapelle-Korrekturen-Traeger_web-372x300.jpg 372w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><p id=\"caption-attachment-542\" class=\"wp-caption-text\">Schematische Rekonstruktion der Kubatur der Burgkapelle St. Pankratius auf dem Bernburger Schlosshof.<\/p><\/div>\n<h1>Ein authentischer Erinnerungsort f\u00fcr die Entstehung Anhalts<\/h1>\n<p>Das vergangene Jahr 2012 stand ganz im Zeichen des Jubil\u00e4ums &#8222;Anhalt 800&#8220;. In Bernburg fand am 20. Oktober 2012 die Abschlussveranstaltung des Festjahres statt.<br \/>\nChronologisch korrekter w\u00e4re es aber gewesen, wenn in der Saalestadt die\u00a0Auftaktveranstaltung ausgetragen worden w\u00e4re, denn Bernburg besitzt einen Ort, der aufs Engste mit der Entstehung Anhalts verbunden ist: die Reste der romanischen Burgkapelle St. Pankratius des Schlosses Bernburg.<\/p>\n<p>Der Termin der Feierlichkeiten im Jahr 2012 kn\u00fcpft sich bekannterma\u00dfen an den Zeitpunkt der vor 800 Jahren erfolgten Erbteilung des Nachlasses des Herzogs <a title=\"Bernhard III. von Sachsen (Wikipedia)\" href=\"http:\/\/de.wikipedia.org\/wiki\/Bernhard_III._(Sachsen)\" target=\"_blank\">Bernhard von Sachsen<\/a>, Sohn Albrechts des B\u00e4ren. W\u00e4hrend Bernhards j\u00fcngerer Sohn Albrecht den s\u00e4chsischen Herzogstitel und die zugeh\u00f6rigen Herrschaftsrechte erhielt, erbte sein \u00e4lterer Bruder Heinrich die Grafschaft Anhalt <span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_1');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_1');\" ><sup id=\"footnote_plugin_tooltip_486_1_1\" class=\"footnote_plugin_tooltip_text\">[1]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_1\" class=\"footnote_tooltip\">Partenheimer, Lutz (2012): 800 Jahre Anhalt &#8211; von der Burg zum &#8222;Land&#8220;, S. 63\u201372 (Partenheimer 2012, S. 66)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_1').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_1', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>.<\/p>\n<p>Bernhard von Sachsen verband sicher viel mit dem Herrschaftssitz Bernburg. Nachdem den Askaniern im Jahr 1152 die Grafschaft Pl\u00f6tzkau zugesprochen wurde, welche auch den Raum um Bernburg bis zur Fuhne umfasste, kaufte sein Vater Albrecht der B\u00e4r im Jahr 1156 ein gr\u00f6\u00dferes Waldgebiet am Ostufer der Saale<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_2');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_2');\" ><sup id=\"footnote_plugin_tooltip_486_1_2\" class=\"footnote_plugin_tooltip_text\">[2]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_2\" class=\"footnote_tooltip\">B\u00f6hlk, Olaf (2012): Warum entstand die Stadt Bernburg? Die Rolle der askanischen Stadtgr\u00fcndung an der Saale bei der Entstehung des sp\u00e4teren Landes Anhalt (21). In: Mitteilungen des Vereins f\u00fcr&nbsp;&#x2026; <span class=\"footnote_tooltip_continue\"  onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_2');\">Continue reading<\/span><\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_2').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_2', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>, welches vermutlich die ehemalige &#8222;civitas Brandanburg&#8220; umgab, deren Verteidigungsanlagen auf dem Bernburger Schlossberg im Jahr 2011 arch\u00e4ologisch nachgewiesen werden konnten<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_3');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_3');\" ><sup id=\"footnote_plugin_tooltip_486_1_3\" class=\"footnote_plugin_tooltip_text\">[3]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_3\" class=\"footnote_tooltip\">Petzschmann, Ulf (2012): Eine karolingisch-ottonische Befestigung und der Friedhof der St. Aegidiengemeinde auf dem Schlossberg von Bernburg (21). In: Mitteilungen des Vereins f\u00fcr Anhaltische&nbsp;&#x2026; <span class=\"footnote_tooltip_continue\"  onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_3');\">Continue reading<\/span><\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_3').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_3', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>.<\/p>\n<p>Auf dieser Grundlage entstand an der Saale eine der gr\u00f6\u00dften romanischen Burganlagen unserer Region und damit ein Machtzentrum, welches die Herrschaft der Askanier \u00fcber das historische Kernland Mitteldeutschlands zwischen Magdeburg und Halle, Elbe und Harz dauerhaft sichern sollte.<\/p>\n<div id=\"attachment_556\" style=\"width: 201px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bogenanfaenger-erdgeschoss.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-556\" class=\"size-medium wp-image-556\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bogenanfaenger-erdgeschoss-191x300.jpg\" alt=\"Eine Pfeilervorlage mit Bogenanf\u00e4nger erm\u00f6glicht die Rekonstruktion der Emporengestaltung im Erdgeschoss.\" width=\"191\" height=\"300\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bogenanfaenger-erdgeschoss-191x300.jpg 191w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bogenanfaenger-erdgeschoss.jpg 383w\" sizes=\"auto, (max-width: 191px) 100vw, 191px\" \/><\/a><p id=\"caption-attachment-556\" class=\"wp-caption-text\">Eine Pfeilervorlage mit Bogenanf\u00e4nger erm\u00f6glicht die Rekonstruktion der Emporengestaltung im Erdgeschoss.<\/p><\/div>\n<p>Vermutlich zogen sich, nach kunsthistorischer Einsch\u00e4tzung,\u00a0die Errichtung\u00a0dieser Burg noch bis in die achtziger Jahre des 12. Jahrhunderts hin. Ein Gro\u00dfteil der Arbeiten fiel also in die Regierungszeit Bernhards, dessen Rolle als Bernburger Burg- und Stadtherr wohl bisher untersch\u00e4tzt wurde. Die Ausstellung einer wichtigen Urkunde in &#8218;domo nostra Berneborch&#8220; zur Jahreswende 1185\/86<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_4');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_4');\" ><sup id=\"footnote_plugin_tooltip_486_1_4\" class=\"footnote_plugin_tooltip_text\">[4]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_4\" class=\"footnote_tooltip\">Nr. 648. In: Otto von Heinemann (Hg.): Codex diplomaticus Anhaltinus. 936-1212. Dessau: Barth i. Comm (I).<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_4').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_4', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>, mit der Bernhard eine bedeutende Schenkung seines 1183 verstorbenen Bruders Dietrich von Werben an das lateinische Kloster in Jerusalem best\u00e4tigte, kennzeichnet das neue askanische Machtzentrum an der Saale bereits als Ort der repr\u00e4sentativen Herrschaftsaus\u00fcbung.<\/p>\n<p>Auch die Kapelle auf der Bernburger Burg wurde zu diesem Zeitpunkt erbaut. Ihr Pankratiuspatrozinium war scheinbar bei den Askaniern beliebt, denn es trat auch beim bereits um 1043 durch den Grafen Esiko (Hesicho) auf der Burg Ballenstedt errichteten Kollegiatstift<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_5');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_5');\" ><sup id=\"footnote_plugin_tooltip_486_1_5\" class=\"footnote_plugin_tooltip_text\">[5]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_5\" class=\"footnote_tooltip\">Schlenker, Gerlinde (2000): Mittelalterliche Kl\u00f6ster im westlichen Anhalt vor allem Ballenstedt, S. 87\u201399 (Schlenker 2000, S. 89)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_5').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_5', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script> und bei dem von den Askaniern \u00fcbernommenen Kloster Hecklingen mit seiner dem Heiligen Georg und Pankratius geweihten Kirche auf.<\/p>\n<p>Mit der Errichtung der Aegidienkirche als Sitz eines Erzpriesters, mit Burglehnh\u00f6fen f\u00fcr die ritterliche Gefolgschaft, einer Siedlung zur landwirtschaftlichen Produktion und der Gr\u00fcndung der Bernburger Altstadt f\u00fcr Kaufleute und Handwerker, bildete Burg und Stadt Bernburg sicher einen w\u00fcrdigen Ort, um Bernhards Rolle als Herzog von Sachsen und potentiellem Kandidaten f\u00fcr die K\u00f6nigskrone symbolisch zu unterstreichen.<\/p>\n<p>Der laut den Annales Stadenses in Bernburg erfolgte Tod Bernhards um den Jahreswechsel 1211\/12 <span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_6');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_6');\" ><sup id=\"footnote_plugin_tooltip_486_1_6\" class=\"footnote_plugin_tooltip_text\">[6]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_6\" class=\"footnote_tooltip\">Lappenberg, Johann Martin (1859): Annales Stadenses auctore M. Alberto ab O. c.-1256 (MGH SS 16). Online verf\u00fcgbar unter <a title=\"http:\/\/www.mgh.de\/dmgh\/resolving\/MGH_SS_16_S._355\" href=\"http:\/\/www.mgh.de\/dmgh\/resolving\/MGH_SS_16_S._355\" target=\"_blank\"><span class=\"footnote_url_wrap\">http:\/\/www.mgh.de\/dmgh\/resolving\/MGH_SS_16_S._355<\/span><\/a> (Lappenberg 1859, S. 355)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_6').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_6', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script> verbindet die Geschichte des Landes Anhalt mit den Mauerresten der Bernburger Burgkapelle, denn hier fand mit hoher Wahrscheinlichkeit der erste Teil der Trauerzeremonie <span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_7');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_7');\" ><sup id=\"footnote_plugin_tooltip_486_1_7\" class=\"footnote_plugin_tooltip_text\">[7]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_7\" class=\"footnote_tooltip\">Zur Trauerzeremonie im Mittelalter: B\u00f6hm, Gabriele (1993): Mittelalterliche fig\u00fcrliche Grabm\u00e4ler in Westfalen. Von den Anf\u00e4ngen bis 1400. M\u00fcnster: Lit (Kunstgeschichte, 19) (B\u00f6hm 1993, S. 123),&nbsp;&#x2026; <span class=\"footnote_tooltip_continue\"  onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_7');\">Continue reading<\/span><\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_7').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_7', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script> f\u00fcr den verstorbenen Herzog statt, bevor sein Leichnam in das Benediktinerkloster Ballenstedt, der Grablege der fr\u00fchen Askanier, \u00fcbergef\u00fchrt wurde.<\/p>\n<p>Die Bernburger Burgkapelle, als Ort der ersten \u00f6ffentlich-rituellen Auseinandersetzung mit dem Tod Bernhards, war somit ein wichtiger Etappenort im zeremoniellen Verlauf des Erbfalls und der askanischen Erbteilung. Sie stellt gewisserma\u00dfen, neben der namengebenden Burg Anhalt im Selketal, eine weitere authentische &#8222;Geburtsst\u00e4tte&#8220; des sp\u00e4teren Landes Anhalt dar.<\/p>\n<div id=\"attachment_557\" style=\"width: 305px\" class=\"wp-caption alignright\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/westliches-suedfenster.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-557\" class=\"size-medium wp-image-557\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/westliches-suedfenster-295x300.jpg\" alt=\"Rechts neben dem westlichen erhaltenen Fenster in der S\u00fcdwand l\u00e4sst sich ein ehemaliger Gew\u00f6lbebogen als helle Verf\u00e4rbung erkennen.\" width=\"295\" height=\"300\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/westliches-suedfenster-295x300.jpg 295w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/westliches-suedfenster.jpg 650w\" sizes=\"auto, (max-width: 295px) 100vw, 295px\" \/><\/a><p id=\"caption-attachment-557\" class=\"wp-caption-text\">Rechts neben dem westlichen erhaltenen Fenster in der S\u00fcdwand l\u00e4sst sich ein ehemaliger Gew\u00f6lbebogen als helle Verf\u00e4rbung erkennen.<\/p><\/div>\n<p>Wiederholt erhielt die Burgkapelle in den folgenden Jahrhunderten Zuwendungen durch die anhaltischen F\u00fcrsten der Bernburger Linie und private Stifter. Quellen berichten<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_8');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_8');\" ><sup id=\"footnote_plugin_tooltip_486_1_8\" class=\"footnote_plugin_tooltip_text\">[8]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_8\" class=\"footnote_tooltip\">Suhle, Hermann (1902): Die St. Pankratiuskapelle auf der Burg Bernburg. In: Unser Anhaltland (2), S. 482\u2013489 (Suhle 1902)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_8').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_8', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script> \u00fcber Bauma\u00dfnahmen und die Errichtung verschiedener Alt\u00e4re, sodass von einer reichen Ausstattung der Bernburger Pankratiuskapelle ausgegangen werden kann. Ihrer Bedeutung entsprechend f\u00fchrte die Kapelle die Liste der bei der Bernburger Teilung im Jahr 1497<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_9');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_9');\" ><sup id=\"footnote_plugin_tooltip_486_1_9\" class=\"footnote_plugin_tooltip_text\">[9]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_9\" class=\"footnote_tooltip\">Nr. 1458. In: Hermann W\u00e4schke (Hg.): Regesten der Urkunden des herzoglichen Haus- und Staatsarchivs zu Zerbst. Aus den Jahren 1401 &#8211; 1500. Dessau: D\u00fcnnhaupt [in Komm.].<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_9').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_9', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script> gemeinschaftlich verwalteten G\u00fcter an, und noch bei der Teilung im Jahr 1515 zwischen den F\u00fcrsten Wolfgang und Ernst stand die Burgkapelle am Anfang der Liste des Gemeinschaftseigentums <span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_10');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_10');\" ><sup id=\"footnote_plugin_tooltip_486_1_10\" class=\"footnote_plugin_tooltip_text\">[10]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_10\" class=\"footnote_tooltip\">Suhle, Hermann (1903): Die St. Pankratiuskapelle auf der Burg Bernburg. In: Unser Anhaltland (3), S. 482\u2013489 (Suhle 1903, S. 488)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_10').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_10', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>.<\/p>\n<p>Ausschlaggebend f\u00fcr ihren Verfall d\u00fcrfte der mit der Reformation eingetretene und verbreitet zu beobachtende Wandel im Umgang mit ehemals wichtigen sakralen Orten gewesen sein. Die Sorge um das Seelenheil der Vorfahren &#8211; im Mittelalter wichtige Motivation zum finanziellen Erhalt von Kapellen und Kl\u00f6stern &#8211; verlor rasch an Bedeutung. Eine mit zahlreichen Alt\u00e4ren ausgestattete Bernburger Schlosskapelle passte kaum zu der im Verlauf des 16. Jahrhunderts aufkommenden calvinistischen Orientierung des F\u00fcrstenhauses.<\/p>\n<p>Wann die Pankratiuskapelle abgebrochen wurde, ist bisher nicht genau bekannt. Vielleicht gibt das benachbarte Portal am &#8222;Krummen Haus&#8220; aus dem Jahr 1565 einen Hinweis auf bauliche Ver\u00e4nderungen in diesem Teil des Schlosses. Letztendlich verlor eine Kapelle in der Kernburg endg\u00fcltig ihre Funktion, als sich F\u00fcrst Christian im Jahr 1625<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_11');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_11');\" ><sup id=\"footnote_plugin_tooltip_486_1_11\" class=\"footnote_plugin_tooltip_text\">[11]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_11\" class=\"footnote_tooltip\">Peper, Hans (1938): Geschichte der Stadt Bernburg. 1. Aufl. Bernburg: Gustav Kunze (Dornbluth Nachf.) (Peper 1938, S. 36)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_11').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_11', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script> entschloss, die Grablege der j\u00fcngeren Bernburger Linie in der bergst\u00e4dter Aegidienkirche einzurichten.<\/p>\n<h1>Bauzustand und Wiederentdeckung<\/h1>\n<p>Johann Christoph Beckmann berichtet in seiner im \u00a0Jahr 1710 erschienenen \u201eHistorie des F\u00fcrstenthums Anhalt&#8220; \u00fcber die St. Pankratiuskapelle: \u201eEs ist aber diese Capelle allgemachlich in Abnehmen gekommen \/ und nachdem die Schlo\u00df-Geb\u00e4ude von Zeit zu Zeit ver\u00e4ndert worden \/ ihr Andenken fast ganz verloschen\u201c<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_12');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_12');\" ><sup id=\"footnote_plugin_tooltip_486_1_12\" class=\"footnote_plugin_tooltip_text\">[12]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_12\" class=\"footnote_tooltip\">Beckmann, Johann Christoph (1999): Historie des F\u00fcrstenthums Anhalt. &#8211; Bd. 3. 1710. Aufl. Dessau: Anhalt. Verlagsges. mbH (Beckmann 1999, S. 124)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_12').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_12', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>.<\/p>\n<div id=\"attachment_495\" style=\"width: 594px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase1.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-495\" class=\"size-large wp-image-495\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase1-1024x823.jpg\" alt=\"Phase 1 - Situation der Reste der Burgkapelle um das Jahr 1900 (bis zum Umbau im Jahr 1972) \" width=\"584\" height=\"469\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase1-1024x823.jpg 1024w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase1-300x241.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase1-373x300.jpg 373w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase1.jpg 1512w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><p id=\"caption-attachment-495\" class=\"wp-caption-text\">Phase 1 &#8211; Situation der Reste der Burgkapelle um das Jahr 1900 (bis zum Umbau im Jahr 1972)<\/p><\/div>\n<p>Erste Nachrichten \u00fcber den Bauzustand im 19. Jahrhundert erhalten wir von Franz B\u00fcttner Pf\u00e4nner zu Thal, der die Reste der Burgkapelle in seinem Werk \u201eDie Kunstdenkmale der Kreise Ballenstedt, Bernburg, K\u00f6then, Dessau, Zerbst\u201c erw\u00e4hnt. Der Autor beschreibt den Zustand der Mauerreste sehr genau und f\u00fcgt seiner Publikation auch eine Skizze der S\u00fcdwand hinzu. Seine Schilderung vermittelt wertvolle Informationen zu heute nicht mehr vorhandenen Gew\u00f6lbe- und Bogenans\u00e4tzen sowie Verzierungen an den Pfeilervorlagen.<\/p>\n<div id=\"attachment_507\" style=\"width: 799px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Buettner-Pfaenner-zu-Thal-s74.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-507\" class=\"size-full wp-image-507\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Buettner-Pfaenner-zu-Thal-s74.jpg\" alt=\"Die \u00e4lteste Darstellung der S\u00fcdwand der Kapelle aus B\u00fcttner Pf\u00e4nner zu Thal, Franz: Die Kunstdenkmale der Kreise Ballenstedt, Bernburg, K\u00f6then, Dessau, Zerbst. Nachdr. [der Ausg.] Dessau, Kahle, 1892 und 1894. Halle: Fliegenkopf-Verl. 1998 (Kunstdenkmalinventare des Landes Sachsen-Anhalt Bd. 13). S. 74. Abbildung Mit freundlicher Genehmigung des Fliegenkopf-Verlages\" width=\"789\" height=\"497\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Buettner-Pfaenner-zu-Thal-s74.jpg 789w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Buettner-Pfaenner-zu-Thal-s74-300x188.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Buettner-Pfaenner-zu-Thal-s74-476x300.jpg 476w\" sizes=\"auto, (max-width: 789px) 100vw, 789px\" \/><\/a><p id=\"caption-attachment-507\" class=\"wp-caption-text\">Die \u00e4lteste Darstellung der S\u00fcdwand der Kapelle aus Franz B\u00fcttner Pf\u00e4nner zu Thal: Die Kunstdenkmale der Kreise Ballenstedt, Bernburg, K\u00f6then, Dessau, Zerbst. Nachdr. [der Ausg.] Dessau, Kahle, 1892 und 1894. Halle: Fliegenkopf-Verl. 1998 (Kunstdenkmalinventare des Landes Sachsen-Anhalt Bd. 13). S. 74. Abbildung mit freundlicher Genehmigung des Fliegenkopf-Verlages<\/p><\/div>Franz B\u00fcttner Pf\u00e4nner zu Thal vermutete schon das Vorhandensein von Fundamenten unter der Oberfl\u00e4che des Schlosshofes und unter dem Erdreich des sich im westlichen Bereich der Kapelle befindlichen Gartens. Dieser Garten geh\u00f6rte zur angrenzenden Wohnung des Kellerschreibers im &#8222;Krummen Haus&#8220;, die sp\u00e4ter vom Kastellan\u00a0der letzten Herzogin, Friederike von Anhalt-Bernburg, und ab 1902 vom Gerichtsdiener und seiner Familie genutzt wurde<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_13');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_13');\" ><sup id=\"footnote_plugin_tooltip_486_1_13\" class=\"footnote_plugin_tooltip_text\">[13]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_13\" class=\"footnote_tooltip\">Suhle, Hermann (1902): Die St. Pankratiuskapelle auf der Burg Bernburg. In: Unser Anhaltland (2), S. 482\u2013489 (Suhle 1902, S. 489)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_13').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_13', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>. \u00dcber dessen breitwillige Zustimmung zur Besichtigung der R\u00e4umlichkeiten \u00e4u\u00dferte sich Herrmann Suhle in seinem 1902 verfassten Aufsatz zur Geschichte der Bernburger Burgkapelle St. Pankratius<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_14');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_14');\" ><sup id=\"footnote_plugin_tooltip_486_1_14\" class=\"footnote_plugin_tooltip_text\">[14]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_14\" class=\"footnote_tooltip\">Suhle, Hermann (1902): Die St. Pankratiuskapelle auf der Burg Bernburg. In: Unser Anhaltland (2), S. 482\u2013489 (Suhle 1902)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_14').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_14', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>. Sp\u00e4ter diente das &#8222;Krummen Haus&#8220;\u00a0als Sitz der Bauverwaltung<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_15');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_15');\" ><sup id=\"footnote_plugin_tooltip_486_1_15\" class=\"footnote_plugin_tooltip_text\">[15]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_15\" class=\"footnote_tooltip\">Wendler, Hans (1937): Die Grundmauern der ehemaligen Burgkapelle auf dem Schlo\u00dfhofe zu Bernburg. In: Anhaltische Geschichtsbl\u00e4tter, 01.01.1937, S. 100\u2013104 (Wendler 1937, S. 102)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_15').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_15', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>.<\/p>\n<p>Suhle setzt sich ausf\u00fchrlich mit den Quellen zur Geschichte der Burgkapelle auseinander, stiftet aber mit seiner These der Unterstellung der Burgkapelle unter die Altst\u00e4dter Marienkirche auch Verwirrung<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_16');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_16');\" ><sup id=\"footnote_plugin_tooltip_486_1_16\" class=\"footnote_plugin_tooltip_text\">[16]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_16\" class=\"footnote_tooltip\">Suhle, Hermann (1902): Die St. Pankratiuskapelle auf der Burg Bernburg. In: Unser Anhaltland (2), S. 482\u2013489 (Suhle 1902, S. 484)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_16').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_16', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>. Richtigerweise muss hingegen festgestellt werden, dass die Burgkapelle stets der Aegidienkirche unterstand<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_17');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_17');\" ><sup id=\"footnote_plugin_tooltip_486_1_17\" class=\"footnote_plugin_tooltip_text\">[17]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_17\" class=\"footnote_tooltip\">B\u00f6hlk, Olaf (2011): Auf den Spuren der Gotik. Die Stadt Bernburg im Mittelalter ; Begleitband zum Kolloquium Stadtgeschichte im Spannungsfeld &#8211; Bernburgs Weg zur fr\u00fchneuzeitlichen&nbsp;&#x2026; <span class=\"footnote_tooltip_continue\"  onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_17');\">Continue reading<\/span><\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_17').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_17', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>.<\/p>\n<p>Eine erste Untersuchung der vermuteten Fundamente fand bei einer vom anhaltischen Staat finanzierten Grabung nach dem Fund von behauenen Steinen bei der Erneuerung einer Feuerl\u00f6schleitung im Jahr 1936 durch den Bernburger Regierungs- und Baurat Hans Wendler statt<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_18');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_18');\" ><sup id=\"footnote_plugin_tooltip_486_1_18\" class=\"footnote_plugin_tooltip_text\">[18]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_18\" class=\"footnote_tooltip\">Wendler, Hans (1937): Die Grundmauern der ehemaligen Burgkapelle auf dem Schlo\u00dfhofe zu Bernburg. In: Anhaltische Geschichtsbl\u00e4tter, 01.01.1937, S. 100\u2013104 (Wendler 1937)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_18').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_18', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>.<\/p>\n<div id=\"attachment_498\" style=\"width: 594px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase2.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-498\" class=\"size-large wp-image-498\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase2-1024x823.jpg\" alt=\"Phase 2 - Schematische Situation bei der Grabung durch Baurat Wendler im Jahr 1936.\" width=\"584\" height=\"469\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase2-1024x823.jpg 1024w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase2-300x241.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase2-373x300.jpg 373w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase2.jpg 1512w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><p id=\"caption-attachment-498\" class=\"wp-caption-text\">Phase 2 &#8211; Schematische Situation bei der Grabung durch Baurat Wendler im Jahr 1936.<\/p><\/div>\n<p>Wendler legte bei seiner Grabung die sich in 1,8 m Tiefe befindlichen Grundmauern<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_19');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_19');\" ><sup id=\"footnote_plugin_tooltip_486_1_19\" class=\"footnote_plugin_tooltip_text\">[19]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_19\" class=\"footnote_tooltip\">Wendler, Hans (1937): Die Grundmauern der ehemaligen Burgkapelle auf dem Schlo\u00dfhofe zu Bernburg. In: Anhaltische Geschichtsbl\u00e4tter, 01.01.1937, S. 100\u2013104 (Wendler 1937, S. 102)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_19').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_19', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script> des Ostabschlusses der Kapelle, bestehend aus halbrunder Apsis und dem Chor frei.<\/p>\n<p>Dann folgte die Untersuchung der S\u00fcdwand und der dort befindlichen Pfeilervorlagen bis zum Kapellenfu\u00dfboden. Dabei stellte Wendler fest, dass sich im Westen des Schiffes eine zweist\u00f6ckige Empore befunden haben m\u00fcsse, deren beide Geschosse eingew\u00f6lbt waren<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_20');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_20');\" ><sup id=\"footnote_plugin_tooltip_486_1_20\" class=\"footnote_plugin_tooltip_text\">[20]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_20\" class=\"footnote_tooltip\">Wendler, Hans (1937): Die Grundmauern der ehemaligen Burgkapelle auf dem Schlo\u00dfhofe zu Bernburg. In: Anhaltische Geschichtsbl\u00e4tter, 01.01.1937, S. 100\u2013104 (Wendler 1937, S. 102\u2013103)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_20').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_20', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>.<\/p>\n<p>Hans Wendler ver\u00f6ffentlichte seine Grabungsergebnisse im Band 13 der \u201eAnhaltischen Geschichtsbl\u00e4tter\u201c und f\u00fcgte dort auch Rekonstruktionszeichnungen des Grundrisses der Burgkapelle bei. Sie zeigen eine der Waldauer Stephanskirche \u00e4hnelnde Anlage, welche bez\u00fcglich der West-Ost-Achse spiegelsymmetrisch aufgebaut war und somit der Idealform des romanischen Dorfkirchentypus mit Schiff, eingezogenem Chor und Apsis entsprach.<\/p>\n<div id=\"attachment_509\" style=\"width: 606px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Wendler-Hans-Die-Grundmauern-der-ehemaligen-Burgkapelle-auf-dem-Schlosshofe-zu-Bernburg-1937-s101.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-509\" class=\"size-full wp-image-509\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Wendler-Hans-Die-Grundmauern-der-ehemaligen-Burgkapelle-auf-dem-Schlosshofe-zu-Bernburg-1937-s101.jpg\" alt=\"Grundriss-Rekonstruktion der Burgkapelle nach Hans Wender aus &quot;Die Grundmauern der ehemaligen Burgkapelle auf dem Schlo\u00dfhofe zu Bernburg. In: Anhaltische Geschichtsbl\u00e4tter (1937). S. 100\u2013104.&quot; S. 101\" width=\"596\" height=\"1000\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Wendler-Hans-Die-Grundmauern-der-ehemaligen-Burgkapelle-auf-dem-Schlosshofe-zu-Bernburg-1937-s101.jpg 596w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Wendler-Hans-Die-Grundmauern-der-ehemaligen-Burgkapelle-auf-dem-Schlosshofe-zu-Bernburg-1937-s101-178x300.jpg 178w\" sizes=\"auto, (max-width: 596px) 100vw, 596px\" \/><\/a><p id=\"caption-attachment-509\" class=\"wp-caption-text\">Grundriss-Rekonstruktion der Burgkapelle nach Hans Wender aus &#8222;Die Grundmauern der ehemaligen Burgkapelle auf dem Schlo\u00dfhofe zu Bernburg. In: Anhaltische Geschichtsbl\u00e4tter (1937). S. 100\u2013104.&#8220; S. 101<\/p><\/div>\n<p>Dieser Grundriss fand \u00fcber die verbreitete Planzeichnung der Schlossanlage von Hermann W\u00e4scher<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_21');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_21');\" ><sup id=\"footnote_plugin_tooltip_486_1_21\" class=\"footnote_plugin_tooltip_text\">[21]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_21\" class=\"footnote_tooltip\">W\u00e4scher, Hermann (1962): Feudalburgen in den Bezirken Halle und Magdeburg. Berlin: Henschel-Verl., S. 218 S ; (W\u00e4scher 1962)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_21').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_21', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script> auch Eingang in j\u00fcngste Publikationen zur Baugeschichte des Bernburger Schlosses, in denen auf die Geschichte der Burgkapelle eingegangen wurde<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_22');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_22');\" ><sup id=\"footnote_plugin_tooltip_486_1_22\" class=\"footnote_plugin_tooltip_text\">[22]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_22\" class=\"footnote_tooltip\">Schmitt, Reinhard (2009): Schloss Bernburg. Leipzig: Ed. Leipzig (Schmitt 2009<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_22').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_22', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script><span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_23');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_23');\" ><sup id=\"footnote_plugin_tooltip_486_1_23\" class=\"footnote_plugin_tooltip_text\">[23]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_23\" class=\"footnote_tooltip\">Schmitt, Reinhard (2008): Die mittelalterliche Burg Bernburg, S. 10\u201345 (Schmitt 2008)<\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_23').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_23', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>.<\/p>\n<p>Hinweise des langj\u00e4hrigen Bernburger Museumsdirektors Herrn Ottomar Tr\u00e4ger lassen aber Zweifel an diesem regelm\u00e4\u00dfigen Grundriss aufkommen.<\/p>\n<div id=\"attachment_500\" style=\"width: 594px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase3.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-500\" class=\"size-large wp-image-500\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase3-1024x823.jpg\" alt=\"Phase 3 - Freilegung des Westteiles unter O. Tr\u00e4ger in den Jahren 1972\/73\" width=\"584\" height=\"469\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase3-1024x823.jpg 1024w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase3-300x241.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase3-373x300.jpg 373w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/phase3.jpg 1512w\" sizes=\"auto, (max-width: 584px) 100vw, 584px\" \/><\/a><p id=\"caption-attachment-500\" class=\"wp-caption-text\">Phase 3 &#8211; Freilegung des Westteiles unter O. Tr\u00e4ger in den Jahren 1972\/73<\/p><\/div>\n<p>In den Jahren 1972-1973 wurde der Westteil der Bernburger Burgkapelle freigelegt, um Museumsbesuchern die Besichtigung dieses wichtigen Bauk\u00f6rpers zu erm\u00f6glichen.<\/p>\n<p>Herr Tr\u00e4ger teilte mir in einem Gespr\u00e4ch mit, dass bei den Freilegungsarbeiten festgestellt wurde, dass die Nordwand der Kapelle im Bereich des Anschlusses an den Chor nicht eingezogen war.\u00a0Hier ergab sich eine deutliche Abweichung zur Rekonstruktion Wendlers, welche zu der Fragestellung f\u00fchrt, ob dieser Bereich tats\u00e4chlich bei der Grabung im Jahr 1936 erfasst wurde.<\/p>\n<div id=\"attachment_511\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-nach-osten.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-511\" class=\"size-full wp-image-511\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-nach-osten.jpg\" alt=\"Foto von der Ausgrabung der Burgkapelle in den Jahren 1972\/73. Die durchlaufende Nordwand an der Abzweigung zur Chorschranke. Blick nach Osten. Abbildung mit freundlicher Genehmigung von Herrn Ottomar Tr\u00e4ger\" width=\"700\" height=\"472\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-nach-osten.jpg 700w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-nach-osten-300x202.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-nach-osten-444x300.jpg 444w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-511\" class=\"wp-caption-text\">Foto von der Ausgrabung der Burgkapelle in den Jahren 1972\/73. Die durchlaufende Nordwand an der Abzweigung zur Chorschranke. Blick nach Osten. Abbildung mit freundlicher Genehmigung von Herrn Ottomar Tr\u00e4ger<\/p><\/div>\n<div id=\"attachment_512\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-auf-chorschranke.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-512\" class=\"size-full wp-image-512\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-auf-chorschranke.jpg\" alt=\"Grabung 1972\/73, Blick vom Rand der Baugrube auf den Abzweig der Chorschranke. Abbildung mit freundlicher Genehmigung von Herrn Ottomar Tr\u00e4ger.\" width=\"700\" height=\"473\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-auf-chorschranke.jpg 700w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-auf-chorschranke-300x202.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-auf-chorschranke-443x300.jpg 443w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-512\" class=\"wp-caption-text\">Grabung 1972\/73, Blick vom Rand der Baugrube auf den Abzweig der Chorschranke. Abbildung mit freundlicher Genehmigung von Herrn Ottomar Tr\u00e4ger.<\/p><\/div>\n<div id=\"attachment_513\" style=\"width: 481px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-nach-osten-neue-wand.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-513\" class=\"size-full wp-image-513\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-nach-osten-neue-wand.jpg\" alt=\"Grabung 1972\/73, Blick auf auf die \u00fcber den Fundamenten der Nordwand neu errichtete Mauer. Die durchg\u00e4ngige Nordwand wurde aufgenommen und auch in der Pflasterung des Schlosshofes an der Kapelle verdeutlicht. Abbildung mit freundlicher Genehmigung von Herrn Ottomar Tr\u00e4ger.\" width=\"471\" height=\"700\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-nach-osten-neue-wand.jpg 471w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/grabung-72-73-nordwand-blick-nach-osten-neue-wand-201x300.jpg 201w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><\/a><p id=\"caption-attachment-513\" class=\"wp-caption-text\">Grabung 1972\/73, Blick auf auf die \u00fcber den Fundamenten der Nordwand neu errichtete Mauer. Die durchg\u00e4ngige Nordwand wurde auch in der Pflasterung des Schlosshofes an der Kapelle verdeutlicht. Abbildung mit freundlicher Genehmigung von Herrn Ottomar Tr\u00e4ger.<\/p><\/div>\n<div id=\"attachment_516\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Ansicht-Burgkapelle-vom-Eulenspiegelturm.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-516\" class=\"size-full wp-image-516\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Ansicht-Burgkapelle-vom-Eulenspiegelturm.jpg\" alt=\"Blick vom Bergfried auf die Burgkapelle, das Pflaster verdeutlicht den Verlauf der Fundamente. Im Vordergrund die durchlaufende Nordwand. Die S\u00fcdwand (an der Treppe zum Portal des &quot;Krummen Hauses&quot;) ist nicht durchg\u00e4ngig, hier ist der Chor eingezogen.\" width=\"600\" height=\"470\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Ansicht-Burgkapelle-vom-Eulenspiegelturm.jpg 600w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Ansicht-Burgkapelle-vom-Eulenspiegelturm-300x235.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Ansicht-Burgkapelle-vom-Eulenspiegelturm-382x300.jpg 382w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-516\" class=\"wp-caption-text\">Blick vom Bergfried auf die Burgkapelle, das Pflaster verdeutlicht den Verlauf der Fundamente. Im Vordergrund die durchlaufende Nordwand. Die S\u00fcdwand (an der Treppe zum Portal des &#8222;Krummen Hauses&#8220;) ist nicht durchg\u00e4ngig, hier ist der Chor eingezogen.<\/p><\/div>\n<p>Scheinbar entsprach die Bernburger Burgkapelle damit doch nicht dem\u00a0achsensymmetrischen\u00a0Idealtyp<span class=\"footnote_referrer\"><a role=\"button\" tabindex=\"0\" onclick=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_24');\" onkeypress=\"footnote_moveToReference_486_1('footnote_plugin_reference_486_1_24');\" ><sup id=\"footnote_plugin_tooltip_486_1_24\" class=\"footnote_plugin_tooltip_text\">[24]<\/sup><\/a><span id=\"footnote_plugin_tooltip_text_486_1_24\" class=\"footnote_tooltip\">Eine gute \u00dcbersicht \u00fcber romanische Dorfkirchentypen gibt die Seite zum Thema <a title=\"Mittelalterliche Dorfkirchen im Teltow (s\u00fcdl. Berlin und Brandenburg) \" href=\"http:\/\/userpage.fu-berlin.de\/engeser\/teltow\/baugeschichte.htm\" target=\"_blank\">Mittelalterliche Dorfkirchen im Teltow (s\u00fcdl. Berlin und Brandenburg)<\/a><\/span><\/span><script type=\"text\/javascript\"> jQuery('#footnote_plugin_tooltip_486_1_24').tooltip({ tip: '#footnote_plugin_tooltip_text_486_1_24', tipClass: 'footnote_tooltip', effect: 'fade', predelay: 0, fadeInSpeed: 200, delay: 400, fadeOutSpeed: 200, position: 'top center', relative: true, offset: [-7, 0], });<\/script>, sondern nahm in ihrem Grundriss R\u00fccksicht auf angrenzende Geb\u00e4ude. Ein Ph\u00e4nomen, welches bei Burgkapellen h\u00e4ufiger beobachtet werden konnte.<\/p>\n<p>Aus dieser Feststellung ergeben sich weitreichende Fragestellungen \u00fcber die Baugestalt der romanischen Burganlage n\u00f6rdlich der Burgkapelle, die aber nur durch weitere arch\u00e4ologische Untersuchungen gekl\u00e4rt werden k\u00f6nnen.<\/p>\n<div id=\"attachment_518\" style=\"width: 510px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/wendler-korrektur.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-518\" class=\"size-full wp-image-518\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/wendler-korrektur.jpg\" alt=\"Rot: Korrektur der Wendler-Pl\u00e4ne. Eine Abweichung von der Symmetrie kann als wichtiger Hinweis auf ein ehemals angrenzendes Geb\u00e4ude aufgefasst werden.\" width=\"500\" height=\"210\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/wendler-korrektur.jpg 500w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/wendler-korrektur-300x126.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><p id=\"caption-attachment-518\" class=\"wp-caption-text\">Rot: Korrektur der Wendler-Pl\u00e4ne. Eine Abweichung von der Symmetrie kann als wichtiger Hinweis auf ein ehemals angrenzendes Geb\u00e4ude aufgefasst werden.<\/p><\/div>\n<h1>Rekonstruktion der Westempore<\/h1>\n<div id=\"attachment_520\" style=\"width: 610px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Burgkapelle-S\u00fcd-West-Ecke-Markierung.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-520\" class=\"size-full wp-image-520\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Burgkapelle-S\u00fcd-West-Ecke-Markierung.jpg\" alt=\"Aufgrund noch erkennbarer Ans\u00e4tze von Gew\u00f6lbe-B\u00f6gen und der Pfeilervorlagen mit Bogenanf\u00e4ngern kann eine schematische Rekonstruktion der Westempore versucht werden.\" width=\"600\" height=\"481\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Burgkapelle-S\u00fcd-West-Ecke-Markierung.jpg 600w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Burgkapelle-S\u00fcd-West-Ecke-Markierung-300x240.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/Burgkapelle-S\u00fcd-West-Ecke-Markierung-374x300.jpg 374w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><p id=\"caption-attachment-520\" class=\"wp-caption-text\">Aufgrund noch erkennbarer Ans\u00e4tze von Gew\u00f6lbe-B\u00f6gen und der Pfeilervorlagen mit Bogenanf\u00e4ngern kann eine schematische Rekonstruktion der Westempore versucht werden.<\/p><\/div>\n<div id=\"attachment_521\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/screenshoot-messpunkte.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-521\" class=\"size-full wp-image-521\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/screenshoot-messpunkte.jpg\" alt=\"Um eine reale Grundlage f\u00fcr ein 3d-Modell zu erzeugen wurden die vorhandenen Baureste photogrammetrisch vermessen.\" width=\"700\" height=\"506\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/screenshoot-messpunkte.jpg 700w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/screenshoot-messpunkte-300x216.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/screenshoot-messpunkte-415x300.jpg 415w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-521\" class=\"wp-caption-text\">Um eine reale Grundlage f\u00fcr ein 3d-Modell zu erhalten, wurden die vorhandenen Baureste photogrammetrisch vermessen.<\/p><\/div>\n<div id=\"attachment_522\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/screenshoot-3d-messpunkte.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-522\" class=\"size-full wp-image-522\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/screenshoot-3d-messpunkte.jpg\" alt=\"Dann erfolgte die \u00dcbetragung der Messpunkte in ein 3d-CAD-System.\" width=\"800\" height=\"524\" \/><\/a><p id=\"caption-attachment-522\" class=\"wp-caption-text\">Dann erfolgte die \u00dcbetragung der Messpunkte in ein 3d-CAD-System.<\/p><\/div>\n<div id=\"attachment_523\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-523\" class=\"size-full wp-image-523\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile.jpg\" alt=\"Die bestehenden Bauteile im 3d-Modell.\" width=\"700\" height=\"606\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile.jpg 700w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-300x259.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-346x300.jpg 346w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-523\" class=\"wp-caption-text\">Die bestehenden Bauteile im 3d-Modell.<\/p><\/div>\n<div id=\"attachment_524\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-524\" class=\"size-full wp-image-524\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore.jpg\" alt=\"Rekonstruktion der Bogen\u00f6ffnungen zum Kirchenschiff aus dem bestehenden Bogenanf\u00e4nger und dem Befund des Mittelpfeilers.\" width=\"700\" height=\"569\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore.jpg 700w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-300x243.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-369x300.jpg 369w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-524\" class=\"wp-caption-text\">Rekonstruktion der Bogen\u00f6ffnungen zum Kirchenschiff aus dem bestehenden Bogenanf\u00e4nger und dem Befund des Mittelpfeilers.<\/p><\/div>\n<div id=\"attachment_525\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og-gewoelbe.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-525\" class=\"size-full wp-image-525\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og-gewoelbe.jpg\" alt=\"Rekonstruktion des Gew\u00f6lbes des Obergeschosses der Empore nach den vorhandenen Gew\u00f6lbeans\u00e4tzen.\" width=\"700\" height=\"601\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og-gewoelbe.jpg 700w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og-gewoelbe-300x257.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og-gewoelbe-349x300.jpg 349w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-525\" class=\"wp-caption-text\">Rekonstruktion des Gew\u00f6lbes des Obergeschosses der Empore nach den vorhandenen Gew\u00f6lbeans\u00e4tzen.<\/p><\/div>\n<div id=\"attachment_526\" style=\"width: 710px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og.jpg\" rel=\"lightbox[486]\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-526\" class=\"size-full wp-image-526\" src=\"http:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og.jpg\" alt=\"Fiktiver schematischer Vorschlag f\u00fcr die Gestaltung der \u00d6ffnung vom Obergeschoss der Westempore zum Kirchenschiff mit drei Arkadenb\u00f6gen und zwei S\u00e4ulen.\" width=\"700\" height=\"601\" srcset=\"https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og.jpg 700w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og-300x257.jpg 300w, https:\/\/www.boehlk.eu\/mittelalterorte\/files\/2013\/01\/bestehende-teile-eg-empore-og-349x300.jpg 349w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/a><p id=\"caption-attachment-526\" class=\"wp-caption-text\">Fiktiver schematischer Vorschlag f\u00fcr die Gestaltung der \u00d6ffnung vom Obergeschoss der Westempore zum Kirchenschiff mit drei Arkadenb\u00f6gen und zwei S\u00e4ulen.<\/p><\/div>\n<h1>Literatur<\/h1>\n<p>[references class=&#8220;compact&#8220; \/]<\/p>\n<div class=\"speaker-mute footnotes_reference_container\"> <div class=\"footnote_container_prepare\"><p><span role=\"button\" tabindex=\"0\" class=\"footnote_reference_container_label pointer\" onclick=\"footnote_expand_collapse_reference_container_486_1();\">Fu\u00dfnoten<\/span><span role=\"button\" tabindex=\"0\" class=\"footnote_reference_container_collapse_button\" style=\"display: none;\" onclick=\"footnote_expand_collapse_reference_container_486_1();\">[<a id=\"footnote_reference_container_collapse_button_486_1\">+<\/a>]<\/span><\/p><\/div> <div id=\"footnote_references_container_486_1\" style=\"\"><table class=\"footnotes_table footnote-reference-container\"><caption class=\"accessibility\">Fu\u00dfnoten<\/caption> <tbody> \r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_1');\"><a id=\"footnote_plugin_reference_486_1_1\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>1<\/a><\/th> <td class=\"footnote_plugin_text\">Partenheimer, Lutz (2012): 800 Jahre Anhalt &#8211; von der Burg zum &#8222;Land&#8220;, S. 63\u201372 (Partenheimer 2012, S. 66)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_2');\"><a id=\"footnote_plugin_reference_486_1_2\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>2<\/a><\/th> <td class=\"footnote_plugin_text\">B\u00f6hlk, Olaf (2012): Warum entstand die Stadt Bernburg? Die Rolle der askanischen Stadtgr\u00fcndung an der Saale bei der Entstehung des sp\u00e4teren Landes Anhalt (21). In: Mitteilungen des Vereins f\u00fcr Anhaltische Landeskunde, S. 109\u2013134 (B\u00f6hlk 2012, S. 126)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_3');\"><a id=\"footnote_plugin_reference_486_1_3\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>3<\/a><\/th> <td class=\"footnote_plugin_text\">Petzschmann, Ulf (2012): Eine karolingisch-ottonische Befestigung und der Friedhof der St. Aegidiengemeinde auf dem Schlossberg von Bernburg (21). In: Mitteilungen des Vereins f\u00fcr Anhaltische Landeskunde, S. 135\u2013148 (Petzschmann 2012)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_4');\"><a id=\"footnote_plugin_reference_486_1_4\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>4<\/a><\/th> <td class=\"footnote_plugin_text\">Nr. 648. In: Otto von Heinemann (Hg.): Codex diplomaticus Anhaltinus. 936-1212. Dessau: Barth i. Comm (I).<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_5');\"><a id=\"footnote_plugin_reference_486_1_5\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>5<\/a><\/th> <td class=\"footnote_plugin_text\">Schlenker, Gerlinde (2000): Mittelalterliche Kl\u00f6ster im westlichen Anhalt vor allem Ballenstedt, S. 87\u201399 (Schlenker 2000, S. 89)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_6');\"><a id=\"footnote_plugin_reference_486_1_6\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>6<\/a><\/th> <td class=\"footnote_plugin_text\">Lappenberg, Johann Martin (1859): Annales Stadenses auctore M. Alberto ab O. c.-1256 (MGH SS 16). Online verf\u00fcgbar unter <a title=\"http:\/\/www.mgh.de\/dmgh\/resolving\/MGH_SS_16_S._355\" href=\"http:\/\/www.mgh.de\/dmgh\/resolving\/MGH_SS_16_S._355\" target=\"_blank\"><span class=\"footnote_url_wrap\">http:\/\/www.mgh.de\/dmgh\/resolving\/MGH_SS_16_S._355<\/span><\/a> (Lappenberg 1859, S. 355)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_7');\"><a id=\"footnote_plugin_reference_486_1_7\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>7<\/a><\/th> <td class=\"footnote_plugin_text\">Zur Trauerzeremonie im Mittelalter: B\u00f6hm, Gabriele (1993): Mittelalterliche fig\u00fcrliche Grabm\u00e4ler in Westfalen. Von den Anf\u00e4ngen bis 1400. M\u00fcnster: Lit (Kunstgeschichte, 19) (B\u00f6hm 1993, S. 123), bez\u00fcglich der Zuordnung der Begr\u00e4bnisse auf der Burg zur Pankratiuskapelle siehe Regest Nr. 513. In: Hermann W\u00e4schke (Hg.): Regesten der Urkunden des herzoglichen Haus- und Staatsarchivs zu Zerbst. Aus den Jahren 1401 &#8211; 1500. Dessau: D\u00fcnnhaupt [in Komm.]<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi\" ><a id=\"footnote_plugin_reference_486_1_8\" class=\"footnote_backlink\" onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_8');\"><span class=\"footnote_index_arrow\">&#8593;<\/span>8,<\/a> <a id=\"footnote_plugin_reference_486_1_14\" class=\"footnote_backlink\" onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_14');\"><span class=\"footnote_index_arrow\">&#8593;<\/span>14<\/a><\/th> <td class=\"footnote_plugin_text\">Suhle, Hermann (1902): Die St. Pankratiuskapelle auf der Burg Bernburg. In: Unser Anhaltland (2), S. 482\u2013489 (Suhle 1902)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_9');\"><a id=\"footnote_plugin_reference_486_1_9\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>9<\/a><\/th> <td class=\"footnote_plugin_text\">Nr. 1458. In: Hermann W\u00e4schke (Hg.): Regesten der Urkunden des herzoglichen Haus- und Staatsarchivs zu Zerbst. Aus den Jahren 1401 &#8211; 1500. Dessau: D\u00fcnnhaupt [in Komm.].<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_10');\"><a id=\"footnote_plugin_reference_486_1_10\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>10<\/a><\/th> <td class=\"footnote_plugin_text\">Suhle, Hermann (1903): Die St. Pankratiuskapelle auf der Burg Bernburg. In: Unser Anhaltland (3), S. 482\u2013489 (Suhle 1903, S. 488)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_11');\"><a id=\"footnote_plugin_reference_486_1_11\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>11<\/a><\/th> <td class=\"footnote_plugin_text\">Peper, Hans (1938): Geschichte der Stadt Bernburg. 1. Aufl. Bernburg: Gustav Kunze (Dornbluth Nachf.) (Peper 1938, S. 36)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_12');\"><a id=\"footnote_plugin_reference_486_1_12\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>12<\/a><\/th> <td class=\"footnote_plugin_text\">Beckmann, Johann Christoph (1999): Historie des F\u00fcrstenthums Anhalt. &#8211; Bd. 3. 1710. Aufl. Dessau: Anhalt. Verlagsges. mbH (Beckmann 1999, S. 124)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_13');\"><a id=\"footnote_plugin_reference_486_1_13\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>13<\/a><\/th> <td class=\"footnote_plugin_text\">Suhle, Hermann (1902): Die St. Pankratiuskapelle auf der Burg Bernburg. In: Unser Anhaltland (2), S. 482\u2013489 (Suhle 1902, S. 489)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi\" ><a id=\"footnote_plugin_reference_486_1_15\" class=\"footnote_backlink\" onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_15');\"><span class=\"footnote_index_arrow\">&#8593;<\/span>15,<\/a> <a id=\"footnote_plugin_reference_486_1_19\" class=\"footnote_backlink\" onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_19');\"><span class=\"footnote_index_arrow\">&#8593;<\/span>19<\/a><\/th> <td class=\"footnote_plugin_text\">Wendler, Hans (1937): Die Grundmauern der ehemaligen Burgkapelle auf dem Schlo\u00dfhofe zu Bernburg. In: Anhaltische Geschichtsbl\u00e4tter, 01.01.1937, S. 100\u2013104 (Wendler 1937, S. 102)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_16');\"><a id=\"footnote_plugin_reference_486_1_16\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>16<\/a><\/th> <td class=\"footnote_plugin_text\">Suhle, Hermann (1902): Die St. Pankratiuskapelle auf der Burg Bernburg. In: Unser Anhaltland (2), S. 482\u2013489 (Suhle 1902, S. 484)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_17');\"><a id=\"footnote_plugin_reference_486_1_17\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>17<\/a><\/th> <td class=\"footnote_plugin_text\">B\u00f6hlk, Olaf (2011): Auf den Spuren der Gotik. Die Stadt Bernburg im Mittelalter ; Begleitband zum Kolloquium Stadtgeschichte im Spannungsfeld &#8211; Bernburgs Weg zur fr\u00fchneuzeitlichen Residenzstadt der F\u00fcrsten von Anhalt. Bernburg (Saale) (Stadtgeschichte im Spannungsfeld, : Bernburgs Weg zur fr\u00fchneuzeitlichen Residenzstadt der F\u00fcrsten von Anhalt \/ F\u00f6rderer der Kulturstiftung e.V. ; Begleitbd.) (B\u00f6hlk 2011, S. 74)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_18');\"><a id=\"footnote_plugin_reference_486_1_18\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>18<\/a><\/th> <td class=\"footnote_plugin_text\">Wendler, Hans (1937): Die Grundmauern der ehemaligen Burgkapelle auf dem Schlo\u00dfhofe zu Bernburg. In: Anhaltische Geschichtsbl\u00e4tter, 01.01.1937, S. 100\u2013104 (Wendler 1937)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_20');\"><a id=\"footnote_plugin_reference_486_1_20\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>20<\/a><\/th> <td class=\"footnote_plugin_text\">Wendler, Hans (1937): Die Grundmauern der ehemaligen Burgkapelle auf dem Schlo\u00dfhofe zu Bernburg. In: Anhaltische Geschichtsbl\u00e4tter, 01.01.1937, S. 100\u2013104 (Wendler 1937, S. 102\u2013103)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_21');\"><a id=\"footnote_plugin_reference_486_1_21\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>21<\/a><\/th> <td class=\"footnote_plugin_text\">W\u00e4scher, Hermann (1962): Feudalburgen in den Bezirken Halle und Magdeburg. Berlin: Henschel-Verl., S. 218 S ; (W\u00e4scher 1962)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_22');\"><a id=\"footnote_plugin_reference_486_1_22\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>22<\/a><\/th> <td class=\"footnote_plugin_text\">Schmitt, Reinhard (2009): Schloss Bernburg. Leipzig: Ed. Leipzig (Schmitt 2009<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_23');\"><a id=\"footnote_plugin_reference_486_1_23\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>23<\/a><\/th> <td class=\"footnote_plugin_text\">Schmitt, Reinhard (2008): Die mittelalterliche Burg Bernburg, S. 10\u201345 (Schmitt 2008)<\/td><\/tr>\r\n\r\n<tr class=\"footnotes_plugin_reference_row\"> <th scope=\"row\" class=\"footnote_plugin_index_combi pointer\"  onclick=\"footnote_moveToAnchor_486_1('footnote_plugin_tooltip_486_1_24');\"><a id=\"footnote_plugin_reference_486_1_24\" class=\"footnote_backlink\"><span class=\"footnote_index_arrow\">&#8593;<\/span>24<\/a><\/th> <td class=\"footnote_plugin_text\">Eine gute \u00dcbersicht \u00fcber romanische Dorfkirchentypen gibt die Seite zum Thema <a title=\"Mittelalterliche Dorfkirchen im Teltow (s\u00fcdl. Berlin und Brandenburg) \" href=\"http:\/\/userpage.fu-berlin.de\/engeser\/teltow\/baugeschichte.htm\" target=\"_blank\">Mittelalterliche Dorfkirchen im Teltow (s\u00fcdl. Berlin und Brandenburg)<\/a><\/td><\/tr>\r\n\r\n <\/tbody> <\/table> <\/div><\/div><script type=\"text\/javascript\"> function footnote_expand_reference_container_486_1() { jQuery('#footnote_references_container_486_1').show(); jQuery('#footnote_reference_container_collapse_button_486_1').text('\u2212'); } function footnote_collapse_reference_container_486_1() { jQuery('#footnote_references_container_486_1').hide(); jQuery('#footnote_reference_container_collapse_button_486_1').text('+'); } function footnote_expand_collapse_reference_container_486_1() { if (jQuery('#footnote_references_container_486_1').is(':hidden')) { footnote_expand_reference_container_486_1(); } else { footnote_collapse_reference_container_486_1(); } } function footnote_moveToReference_486_1(p_str_TargetID) { footnote_expand_reference_container_486_1(); var l_obj_Target = jQuery('#' + p_str_TargetID); if (l_obj_Target.length) { jQuery( 'html, body' ).delay( 0 ); jQuery('html, body').animate({ scrollTop: l_obj_Target.offset().top - window.innerHeight * 0.2 }, 380); } } function footnote_moveToAnchor_486_1(p_str_TargetID) { footnote_expand_reference_container_486_1(); var l_obj_Target = jQuery('#' + p_str_TargetID); if (l_obj_Target.length) { jQuery( 'html, body' ).delay( 0 ); jQuery('html, body').animate({ scrollTop: l_obj_Target.offset().top - window.innerHeight * 0.2 }, 380); } }<\/script>","protected":false},"excerpt":{"rendered":"<p>Ein authentischer Erinnerungsort f\u00fcr die Entstehung Anhalts Das vergangene Jahr 2012 stand ganz im Zeichen des Jubil\u00e4ums &#8222;Anhalt 800&#8220;. In Bernburg fand am 20. Oktober 2012 die Abschlussveranstaltung des Festjahres statt. Chronologisch korrekter w\u00e4re es aber gewesen, wenn in der &hellip; <a href=\"https:\/\/www.boehlk.eu\/mittelalterorte\/die-bernburger-burgkapelle-st-pankratius\/\">Weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":546,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"sidebar-page.php","meta":{"footnotes":""},"class_list":["post-486","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.boehlk.eu\/mittelalterorte\/wp-json\/wp\/v2\/pages\/486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.boehlk.eu\/mittelalterorte\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.boehlk.eu\/mittelalterorte\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.boehlk.eu\/mittelalterorte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boehlk.eu\/mittelalterorte\/wp-json\/wp\/v2\/comments?post=486"}],"version-history":[{"count":49,"href":"https:\/\/www.boehlk.eu\/mittelalterorte\/wp-json\/wp\/v2\/pages\/486\/revisions"}],"predecessor-version":[{"id":702,"href":"https:\/\/www.boehlk.eu\/mittelalterorte\/wp-json\/wp\/v2\/pages\/486\/revisions\/702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.boehlk.eu\/mittelalterorte\/wp-json\/wp\/v2\/media\/546"}],"wp:attachment":[{"href":"https:\/\/www.boehlk.eu\/mittelalterorte\/wp-json\/wp\/v2\/media?parent=486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}